{"id":37141,"date":"2021-01-22T14:35:32","date_gmt":"2021-01-22T12:35:32","guid":{"rendered":"https:\/\/www.hostinet.com\/formacion\/?p=37141"},"modified":"2021-02-12T11:49:14","modified_gmt":"2021-02-12T09:49:14","slug":"wordpress-hackeado-como-cambiar-las-contrasenas-de-todo","status":"publish","type":"post","link":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/","title":{"rendered":"WordPress Hackeado &#8211; C\u00f3mo Cambiar las Contrase\u00f1as de Todo"},"content":{"rendered":" <!-- x0 --><div style=\"min-height: 30px; margin-top: 0px; padding-bottom: 7px; z-index: 1;position: relative; float: none;\" class=\"social-container\"><\/div><h4><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37153\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas.jpg\" alt=\"WordPress Hackeado - C\u00f3mo Cambiar las Contrase\u00f1as de Todo\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas.jpg 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas-500x333.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas-350x233.jpg 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/h4>\n<h4>Si recibes un email de Hostinet como \u00abAviso C\u00f3digo Malicioso\u00bb en tu WordPress, una de las cosas que debes hacer es cambiar las contrase\u00f1as de todo, \u00a1todo!<br \/>\nEsto crea algunas confusiones entre los usuarios, pero hoy vamos a aclararlo paso a paso.<\/h4>\n<p><strong>Tu WordPress ha sido hackeado<\/strong>. Recibes un email de Hostinet indic\u00e1ndote que hemos <strong>detectado malware instalado en tu sitio<\/strong> y este ha sido bloqueado temporalmente por seguridad.<\/p>\n<p>Si es la primera vez que te pasa esto, <strong>no entres en p\u00e1nico<\/strong>, en la gran mayor\u00eda de los casos el problema se soluciona en el mismo d\u00eda.<\/p>\n<p><strong>Tan s\u00f3lo tienes que seguir las instrucciones<\/strong> del email que has recibido y listo, <strong>tu sitio WordPress volver\u00e1 a estar seguro y activo<\/strong> como si nada hubiera pasado.<\/p>\n<p>Una de las acciones que se indican en el email, es el cambio de contrase\u00f1as:<\/p>\n<pre><code>- Modifique la contrase\u00f1a de acceso a su gestor de contenidos si fuera el caso y a su panel de control cPanel desde la secci\u00f3n Preferencias, aseg\u00farese de usar una contrase\u00f1a de acceso segura.\r\n<\/code><\/pre>\n<p>&nbsp;<\/p>\n<p>En algunos usuarios esto causa confusi\u00f3n. <strong>\u00bfQu\u00e9 contrase\u00f1as? \u00bfDesde d\u00f3nde las cambio?<\/strong>. Al fin de al cabo no es algo que se haga todos los d\u00edas y puede costar un poco.<\/p>\n<p>En este art\u00edculo te vamos a ense\u00f1ar a <strong>cambiar la contrase\u00f1a de WordPress<\/strong>, del panel de control <strong>cPanel<\/strong> y hasta de <strong>la base de datos<\/strong>, que es m\u00e1s f\u00e1cil de lo que parece.<\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.hostinet.com\/hosting-web\/\" target=\"_blank\"><img decoding=\"async\" class=\"alignnone size-full\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2024\/03\/banner_hostinet_generico.jpg\" alt=\"Hosting Gen\u00e9rico\"><\/a><\/p>\n<hr \/>\n<p><center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/uCtdG6dbk4o\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/center><\/p>\n<h2>C\u00f3mo Cambiar la Contrase\u00f1a del Administrador de WordPress<\/h2>\n<p>Si eres el \u00fanico que accede a WordPress para publicar post o cambiar aspectos del dise\u00f1o, <strong>lo m\u00e1s seguro es que seas el administrador<\/strong>.<\/p>\n<p>Si es otra persona la que se encarga de esto, ser\u00e1 esta persona la que tendr\u00e1 que cambiar la contrase\u00f1a.<\/p>\n<p>Cambiar la contrase\u00f1a del administrador de WordPress es muy f\u00e1cil y se hace desde el propio WordPress, as\u00ed que lo primero que tienes que hacer es <strong>acceder a tu WordPress de la forma habitual<\/strong>:<\/p>\n<pre><code>https:\/\/midominio.info\/wp-admin\r\n<\/code><\/pre>\n<p>&nbsp;<\/p>\n<p>En la esquina superior derecha ver\u00e1s un <strong>\u00abHola, xxxx\u00bb<\/strong> seguido de tu avatar. Si haces click ah\u00ed, ver\u00e1s que tienes un opci\u00f3n que dice <strong>Editar el Perfil<\/strong>, ese es el objetivo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37150\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-editar-perfil-administrador.jpg\" alt=\"wordpress editar perfil administrador\" width=\"464\" height=\"220\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-editar-perfil-administrador.jpg 464w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-editar-perfil-administrador-350x166.jpg 350w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/><\/p>\n<p>El perfil de WordPress no es el m\u00e1s amigable del mundo, pero si bajas un poco ver\u00e1s que tienes una opci\u00f3n llamada <strong>Gesti\u00f3n de la Cuenta<\/strong> y ah\u00ed tendr\u00e1s dos opciones:<\/p>\n<ul>\n<li><strong>&#8211; Nueva Contrase\u00f1a<\/strong><br \/>\nS\u00f3lo tienes que pulsar ah\u00ed y establecer la nueva contrase\u00f1a que quieres utilizar**<\/li>\n<li><strong>&#8211; Sesiones<\/strong><br \/>\nPara desconectar cualquier otras sesi\u00f3n que est\u00e9 conectada en otra parte. \u00datil para asegurarse de que ning\u00fan hacker quede conectado una vez hayas cambiado la contrase\u00f1a.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37151\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-gestion-cuenta-cambiar-contrasena.jpg\" alt=\"wordpress gestion cuenta cambiar contrasena\" width=\"532\" height=\"243\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-gestion-cuenta-cambiar-contrasena.jpg 532w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-gestion-cuenta-cambiar-contrasena-500x228.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-gestion-cuenta-cambiar-contrasena-350x160.jpg 350w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a1Importante!<\/strong> Tienes que guardar los cambios. Abajo del todo ver\u00e1s un bot\u00f3n que pone <strong>Actualizar Perfil<\/strong>, as\u00ed que primero pones la contrase\u00f1a que quieres utilizar y despu\u00e9s haces click en el bot\u00f3n para guardar los cambios.<\/p>\n<p><strong>\u00a1Importante 2!<\/strong> L contrase\u00f1a que pongas ser\u00e1 la que tengas que utilizar a partir de ese momento para acceder a tu WordPress. <strong>\u00a1No la olvides!<\/strong><\/p>\n<h2>C\u00f3mo Cambiar la Contrase\u00f1a del Panel de Control cPanel<\/h2>\n<p>Ahora toca cambiar la contrase\u00f1a de <strong>cPanel<\/strong>, que es el panel de control al que <strong>Hostinet te da accedo al contratar un hosting<\/strong> (excepto en los hosting Windows que usan otro panel)<\/p>\n<p><strong>Si no la tienes o no la recuerdas<\/strong>, puedes ponerte en contacto con el soporte t\u00e9cnico de Hostinet y te enviaremos una nueva contrase\u00f1a a tu cuenta de correo.<\/p>\n<p>En este caso, ya estar\u00eda todo hecho porque la contrase\u00f1a la cambiar\u00edamos nosotros, pero <strong>si tienes claro el acceso a cPanel y quieres cambiarla t\u00fa mismo<\/strong>, tambi\u00e9n es muy sencillo.<\/p>\n<p>Cuando accedas a cPanel, <strong>ver\u00e1s el nombre de usuario de cPanel en la parte superior derecha<\/strong> de la pantalla, como en el panel de WordPress.<\/p>\n<p>Si haces click ver\u00e1s una opci\u00f3n que dice <strong>Seguridad de la Contrase\u00f1a<\/strong>, aunque en realidad ver\u00e1s un car\u00e1cter <em>\u00ab&amp;\u00bb<\/em> en medio que se trata de un peque\u00f1o <em>bug<\/em> del panel. No le des importancia y <strong>haz click ah\u00ed<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37144\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-cambiar-contrasena.jpg\" alt=\"cpanel cambiar contrasena de cuenta\" width=\"600\" height=\"352\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-cambiar-contrasena.jpg 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-cambiar-contrasena-500x293.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-cambiar-contrasena-350x205.jpg 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>En la siguiente pantalla ver\u00e1s que tienes tres campos:<\/p>\n<ul>\n<li><strong>&#8211; Contrase\u00f1a Anterior<\/strong><\/li>\n<li><strong>&#8211; Nueva Contrase\u00f1a<\/strong><\/li>\n<li><strong>&#8211; Nueva Contrase\u00f1a (nuevamente)<\/strong><\/li>\n<\/ul>\n<p><strong>Como ver\u00e1s no hay mucho que explica aqu\u00ed<\/strong>. S\u00f3lo tienes que tener en cuenta que te pedir\u00e1 un m\u00ednimo de seguridad, con may\u00fasculas, s\u00edmbolos y todo eso.<\/p>\n<p>Tienes un bot\u00f3n para generar una nueva contrase\u00f1a aleatoria y muy segura que puedes utilizar, <strong>\u00a1\u00a1pero recuerda apuntarla bien en alg\u00fan sitio seguro!!<\/strong> (El pos-it pegado a la pantalla no es un sitio seguro)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37145\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-cambiar-contrasena-ahora.jpg\" alt=\"cpanel cambiar contrasena ahora\" width=\"600\" height=\"453\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-cambiar-contrasena-ahora.jpg 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-cambiar-contrasena-ahora-500x378.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-cambiar-contrasena-ahora-350x264.jpg 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Recuerda tambi\u00e9n que tienes que hacer click en el bot\u00f3n que pone <strong>Cambie su Contrase\u00f1a Ahora<\/strong> para que se guarde los cambios.<\/p>\n<p>Y con esto ya estar\u00edan cambiada, por cierto, cPanel te <em>\u00abtirar\u00e1\u00bb<\/em> una vez cambies la contrase\u00f1a, ya que te has logueado con la contrase\u00f1a antigua y esa ya no ser\u00e1 v\u00e1lida.<\/p>\n<h2>C\u00f3mo Cambiar la Contrase\u00f1a de la Base de Datos de WordPress<\/h2>\n<p><strong>La contrase\u00f1a de la base de datos de WordPress es m\u00e1s complicada de cambiar<\/strong> y no es necesario hacerlo en la mayor\u00eda de los casos, de hecho no se solicita en el email que se env\u00eda al detectar malware.<\/p>\n<p>Pero en algunos casos si que es necesario y recomendable y si lo haces una vez, ver\u00e1s que no es tan complicado como parece y el plus de seguridad que ofrece es importante.<\/p>\n<p>El cambio se hace desde cPanel. <strong>Se cambia la contrase\u00f1a<\/strong> y luego <strong>hay que decirle a WordPress que cu\u00e1l es la nueva contrase\u00f1a<\/strong>.<\/p>\n<p>Primero puedes empezar por localizar el archivo de configuraci\u00f3n de WordPress, que se llama <strong>wp-config.php<\/strong>.<\/p>\n<p>Desde <strong>cPanel &gt; Administrador de Archivos &gt; public_html<\/strong> deber\u00edas de localizarlo. F\u00edjate en la imagen:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-30943\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2019\/09\/localizar-wp-config-600x405.jpg\" alt=\"localizar wp-config - cpanel\" width=\"600\" height=\"405\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2019\/09\/localizar-wp-config.jpg 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2019\/09\/localizar-wp-config-500x338.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2019\/09\/localizar-wp-config-350x236.jpg 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Si WordPress no est\u00e1 instalado en la carpeta <strong>public_html<\/strong>, si est\u00e1 en otras carpeta o en un subdominio, el archivo estar\u00e1 ah\u00ed, pero por defecto se instala en <strong>public_html<\/strong>.<\/p>\n<p>SI haces click con el bot\u00f3n derecho sobre este archivo, ver\u00e1s que tienes una opci\u00f3n que pone <strong>Edit<\/strong>, haz click ah\u00ed (las 2 veces) y te abrir\u00e1 una nueva ventana con el c\u00f3digo del archivo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21633\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2015\/03\/wp-config-bd-datos.jpg\" alt=\"wp-config bd datos\" width=\"430\" height=\"500\" \/><\/p>\n<p>Si no lo has visto nunca te intimidar\u00e1 un poco. Son un mont\u00f3n de l\u00edneas de c\u00f3digo y <strong>da miedo que vayas a romper algo<\/strong>, pero <strong>si sigues esta gu\u00eda no deber\u00edas tener problemas<\/strong>.<\/p>\n<p>Si te fijas en el c\u00f3digo, en las l\u00edneas que van desde la 22 a la 27 est\u00e1 la informaci\u00f3n de la base de datos, nombre, usuario y contrase\u00f1a.<\/p>\n<p>No toques nada por ahora, s\u00f3lo f\u00edjate en el nombre del usuario de la base de datos (DB_USER):<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37148\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/usuario-base-datos-anotar.jpg\" alt=\"usuario base datos anotar para cambiar contrase\u00f1a\" width=\"567\" height=\"243\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/usuario-base-datos-anotar.jpg 567w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/usuario-base-datos-anotar-500x214.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/usuario-base-datos-anotar-350x150.jpg 350w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/p>\n<p>Deja la ventana con el c\u00f3digo del archivo wp-admin.php abierta y vuelve a cpanel.<\/p>\n<p>Ahora ves al apartado <strong>Bases de Datos<\/strong> y haz click en <strong>Bases de Datos MySQL<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16270\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2008\/09\/bases-de-datos-mysql.jpg\" alt=\"bases de datos mysql en cPanel\" width=\"500\" height=\"79\" \/><\/p>\n<p>Si s\u00f3lo tienes un WordPress solo tendr\u00e1s un usuario y una base de datos, pero si tiene m\u00e1s cosas instaladas, <strong>debes buscar el usuario has visto en el archivo de configuraci\u00f3n<\/strong>.<\/p>\n<p>Justo al lado del usuario ver\u00e1s un icono de una llave y el texto <strong>Cambiar Contrase\u00f1a<\/strong>. Creo que ya intuyes lo que tienes que hacer \ud83d\ude42<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37146\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-usuario-bbdd-cambiar-contrasena.jpg\" alt=\"cpanel usuario bbdd cambiar contrasena wordpress\" width=\"600\" height=\"375\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-usuario-bbdd-cambiar-contrasena.jpg 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-usuario-bbdd-cambiar-contrasena-500x313.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/cpanel-usuario-bbdd-cambiar-contrasena-350x219.jpg 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Pulsa en <strong>Cambiar Contrase\u00f1a<\/strong> y en la siguiente pantalla te recomendamos que utilices el bot\u00f3n de <strong>Generador de Contrase\u00f1as<\/strong>.<\/p>\n<p><strong>Anota bien la contrase\u00f1a que se genera<\/strong>, sin espacios en blanco delante o detr\u00e1s, marca la casilla que dice <em>\u00abHe copiado esta contrase\u00f1a en un lugar seguro\u00bb<\/em> y despu\u00e9s pulsa en <strong>Usar Contrase\u00f1a<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37147\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/generar-contrasena-bbdd-segura.jpg\" alt=\"generar contrasena bbdd segura\" width=\"600\" height=\"448\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/generar-contrasena-bbdd-segura.jpg 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/generar-contrasena-bbdd-segura-500x373.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/generar-contrasena-bbdd-segura-350x261.jpg 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Despu\u00e9s solo quedar\u00e1 hacer click en <strong>Cambiar Contrase\u00f1a<\/strong> para guarda la nueva contrase\u00f1a.<\/p>\n<p><strong>\u00a1IMPORTANTE!<\/strong> Al cambiar la contrase\u00f1a de la base de datos, <strong>WordPress dejar\u00e1 de funcionar<\/strong>. Dar\u00e1 un error de conexi\u00f3n a la base de dato, porque hemos cambiado la contrase\u00f1a.<\/p>\n<p>As\u00ed que ahora volvemos al archivo de configuraci\u00f3n <strong>wp-config.php<\/strong> que hab\u00edamos dejado abierto y en la l\u00ednea que dice <strong>DB_PASSWORD<\/strong>, debemos poner la nueva contrase\u00f1a que hemos generado y apuntado.<\/p>\n<p><strong>Las comillas son como las paredes<\/strong>, no hay que cambiarlas ni borrarlas y sobre todo, <strong>no dejar ning\u00fan hueco en blanco<\/strong> entre ellas y la contrase\u00f1a.<\/p>\n<p>En esta imagen <strong>puedes ver c\u00f3mo tienes que poner<\/strong> la nueva contrase\u00f1a:<\/p>\n<p>Despu\u00e9s no te olvides de <strong>Guardarlo Cambios<\/strong> en la parte de arriba a la derecha y con esto <strong>ya estar\u00eda cambiada la contrase\u00f1a de la base de datos<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2>Hosting WordPress en Hostinet con IP Espa\u00f1ola + SSD + LiteSpeed<\/h2>\n<p><a href=\"https:\/\/www.hostinet.com\/hosting-wordpress\/\" target=\"_blank\"><img decoding=\"async\" class=\"alignnone size-full\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2026\/03\/banner_hosting_wordpress.jpg\" alt=\"Hosting WordPress\"><\/a><\/p>\n<div style=\"min-height: 30px; margin-top: 0px; padding-bottom: 7px; z-index: 1;position: relative; float: none;\" class=\"social-container\"><\/div> <!-- x1 -->","protected":false},"excerpt":{"rendered":"<p>Si recibes un email de Hostinet como \u00abAviso C\u00f3digo Malicioso\u00bb en tu WordPress, una de las cosas que debes hacer es cambiar las contrase\u00f1as de todo, \u00a1todo! Esto crea algunas confusiones entre los usuarios, pero hoy vamos a aclararlo paso a paso. Tu WordPress ha sido hackeado. Recibes un email\u2026 <\/p>\n<div class=\"post-more\">\n<p><a class=\"btn button\" href=\"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/\">Sigue leyendo &rarr;<\/a><\/p>\n<\/div>\n","protected":false},"author":14,"featured_media":37153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1783],"tags":[],"class_list":["post-37141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordpress"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WordPress Hackeado - C\u00f3mo Cambiar las Contrase\u00f1as de Todo<\/title>\n<meta name=\"description\" content=\"Si recibes un email de Hostinet como &quot;Aviso C\u00f3digo Malicioso&quot; en tu WordPress, una de las cosas que debes hacer es cambiar las contrase\u00f1as de todo, \u00a1todo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WordPress Hackeado - C\u00f3mo Cambiar las Contrase\u00f1as de Todo\" \/>\n<meta property=\"og:description\" content=\"Si recibes un email de Hostinet como &quot;Aviso C\u00f3digo Malicioso&quot; en tu WordPress, una de las cosas que debes hacer es cambiar las contrase\u00f1as de todo, \u00a1todo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/\" \/>\n<meta property=\"og:site_name\" content=\"Hostinet\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-22T12:35:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-12T09:49:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marce Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Hostinet\" \/>\n<meta name=\"twitter:site\" content=\"@Hostinet\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marce Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/\"},\"author\":{\"name\":\"Marce Medina\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/person\\\/c30f2ada08e5d4836b12fd3782d3958f\"},\"headline\":\"WordPress Hackeado &#8211; C\u00f3mo Cambiar las Contrase\u00f1as de Todo\",\"datePublished\":\"2021-01-22T12:35:32+00:00\",\"dateModified\":\"2021-02-12T09:49:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/\"},\"wordCount\":1477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/wordpress-hackeado-cambiar-contrasenas.jpg\",\"articleSection\":[\"Wordpress\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/\",\"name\":\"WordPress Hackeado - C\u00f3mo Cambiar las Contrase\u00f1as de Todo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/wordpress-hackeado-cambiar-contrasenas.jpg\",\"datePublished\":\"2021-01-22T12:35:32+00:00\",\"dateModified\":\"2021-02-12T09:49:14+00:00\",\"description\":\"Si recibes un email de Hostinet como \\\"Aviso C\u00f3digo Malicioso\\\" en tu WordPress, una de las cosas que debes hacer es cambiar las contrase\u00f1as de todo, \u00a1todo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/wordpress-hackeado-cambiar-contrasenas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/wordpress-hackeado-cambiar-contrasenas.jpg\",\"width\":600,\"height\":400,\"caption\":\"WordPress Hackeado - C\u00f3mo Cambiar las Contrase\u00f1as de Todo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wordpress\\\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wordpress\",\"item\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/category\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WordPress Hackeado &#8211; C\u00f3mo Cambiar las Contrase\u00f1as de Todo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#website\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\",\"name\":\"Hostinet\",\"description\":\"Hosting y dominios en Espa\u00f1a. La mejor calidad a precios baratos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\",\"name\":\"Hostinet SLU\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/hostinet-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/hostinet-logo.jpg\",\"width\":600,\"height\":245,\"caption\":\"Hostinet SLU\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Hostinet\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/person\\\/c30f2ada08e5d4836b12fd3782d3958f\",\"name\":\"Marce Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g\",\"caption\":\"Marce Medina\"},\"sameAs\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WordPress Hackeado - C\u00f3mo Cambiar las Contrase\u00f1as de Todo","description":"Si recibes un email de Hostinet como \"Aviso C\u00f3digo Malicioso\" en tu WordPress, una de las cosas que debes hacer es cambiar las contrase\u00f1as de todo, \u00a1todo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/","og_locale":"es_ES","og_type":"article","og_title":"WordPress Hackeado - C\u00f3mo Cambiar las Contrase\u00f1as de Todo","og_description":"Si recibes un email de Hostinet como \"Aviso C\u00f3digo Malicioso\" en tu WordPress, una de las cosas que debes hacer es cambiar las contrase\u00f1as de todo, \u00a1todo!","og_url":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/","og_site_name":"Hostinet","article_published_time":"2021-01-22T12:35:32+00:00","article_modified_time":"2021-02-12T09:49:14+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas.jpg","type":"image\/jpeg"}],"author":"Marce Medina","twitter_card":"summary_large_image","twitter_creator":"@Hostinet","twitter_site":"@Hostinet","twitter_misc":{"Escrito por":"Marce Medina","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/#article","isPartOf":{"@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/"},"author":{"name":"Marce Medina","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/person\/c30f2ada08e5d4836b12fd3782d3958f"},"headline":"WordPress Hackeado &#8211; C\u00f3mo Cambiar las Contrase\u00f1as de Todo","datePublished":"2021-01-22T12:35:32+00:00","dateModified":"2021-02-12T09:49:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/"},"wordCount":1477,"commentCount":0,"publisher":{"@id":"https:\/\/www.hostinet.com\/formacion\/#organization"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas.jpg","articleSection":["Wordpress"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/","url":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/","name":"WordPress Hackeado - C\u00f3mo Cambiar las Contrase\u00f1as de Todo","isPartOf":{"@id":"https:\/\/www.hostinet.com\/formacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/#primaryimage"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas.jpg","datePublished":"2021-01-22T12:35:32+00:00","dateModified":"2021-02-12T09:49:14+00:00","description":"Si recibes un email de Hostinet como \"Aviso C\u00f3digo Malicioso\" en tu WordPress, una de las cosas que debes hacer es cambiar las contrase\u00f1as de todo, \u00a1todo!","breadcrumb":{"@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/#primaryimage","url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas.jpg","contentUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2021\/01\/wordpress-hackeado-cambiar-contrasenas.jpg","width":600,"height":400,"caption":"WordPress Hackeado - C\u00f3mo Cambiar las Contrase\u00f1as de Todo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hostinet.com\/formacion\/wordpress\/wordpress-hackeado-como-cambiar-las-contrasenas-de-todo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hostinet.com\/formacion\/"},{"@type":"ListItem","position":2,"name":"Wordpress","item":"https:\/\/www.hostinet.com\/formacion\/category\/wordpress\/"},{"@type":"ListItem","position":3,"name":"WordPress Hackeado &#8211; C\u00f3mo Cambiar las Contrase\u00f1as de Todo"}]},{"@type":"WebSite","@id":"https:\/\/www.hostinet.com\/formacion\/#website","url":"https:\/\/www.hostinet.com\/formacion\/","name":"Hostinet","description":"Hosting y dominios en Espa\u00f1a. La mejor calidad a precios baratos","publisher":{"@id":"https:\/\/www.hostinet.com\/formacion\/#organization"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hostinet.com\/formacion\/#organization","name":"Hostinet SLU","url":"https:\/\/www.hostinet.com\/formacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/logo\/image\/","url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/06\/hostinet-logo.jpg","contentUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/06\/hostinet-logo.jpg","width":600,"height":245,"caption":"Hostinet SLU"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Hostinet"]},{"@type":"Person","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/person\/c30f2ada08e5d4836b12fd3782d3958f","name":"Marce Medina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g","caption":"Marce Medina"},"sameAs":["https:\/\/www.hostinet.com\/formacion\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/37141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/comments?post=37141"}],"version-history":[{"count":5,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/37141\/revisions"}],"predecessor-version":[{"id":37400,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/37141\/revisions\/37400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/media\/37153"}],"wp:attachment":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/media?parent=37141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/categories?post=37141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/tags?post=37141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}