{"id":34670,"date":"2020-05-26T17:30:26","date_gmt":"2020-05-26T15:30:26","guid":{"rendered":"https:\/\/www.hostinet.com\/formacion\/?p=34670"},"modified":"2020-05-26T17:30:26","modified_gmt":"2020-05-26T15:30:26","slug":"activar-modo-catalogo-prestashop17","status":"publish","type":"post","link":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/","title":{"rendered":"Activar Modo Cat\u00e1logo en Prestashop 1.7"},"content":{"rendered":" <!-- x0 --><div style=\"min-height: 30px; margin-top: 0px; padding-bottom: 7px; z-index: 1;position: relative; float: none;\" class=\"social-container\"><\/div><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-34672\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo-600x298.jpg\" alt=\"PrestaShop 1.7 modo cat\u00e1logo\" width=\"600\" height=\"298\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo.jpg 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo-500x248.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo-350x174.jpg 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Aunque puede resultar un tanto curioso debido a la simplicidad del asunto, a veces en Hostinet recibimos consultas de nuestros clientes en la que nos indican como pueden <strong>activar el modo cat\u00e1logo en PrestaShop 1.7<\/strong>, es por ello por lo que en el d\u00eda de hoy vamos a indicar donde se ubica esta opci\u00f3n dentro del panel de administraci\u00f3n del CMS.<\/p>\n<p>Lo primero de todo indicar que <strong>PrestaShop 1.7<\/strong>, al igual que otras versiones m\u00e1s antiguas del CMS, viene por defecto con el <strong>modo cat\u00e1logo integrado<\/strong> y para aprovecharse del mismo lo \u00fanico que hay que hacer es activarlo.<\/p>\n<p>En fin, no vamos a irnos por las ramas y directamente vamos a comentar c\u00f3mo se puede activar el modo cat\u00e1logo en PrestaShop 1.7, desde dentro del <em>Backoffice<\/em> del CMS.<\/p>\n<h3><em>Para ello, tan solo tenemos que seguir estos sencillos pasos:<\/em><\/h3>\n<p><strong>Bloque CONFIGURAR -&gt; Par\u00e1metros de la Tienda -&gt; Configuraci\u00f3n de productos -&gt; Modo cat\u00e1logo<\/strong>. Y aqu\u00ed marcamos el <strong>\u201cS\u00ed\u201d<\/strong>, esta acci\u00f3n al mismo tiempo lo que har\u00e1 es habilitar otra opci\u00f3n nueva para que indiquemos si queremos mostrar los precios o no.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-34674\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-activar-catalogo-600x327.jpg\" alt=\"PrestaShop 1.7 Activar Cat\u00e1logo\" width=\"600\" height=\"327\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-activar-catalogo.jpg 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-activar-catalogo-500x273.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-activar-catalogo-350x191.jpg 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Despu\u00e9s, no se nos puede olvidar pinchar en el bot\u00f3n <strong>Guardar<\/strong>, ubicado abajo a la izquierda, ya que de lo contrario nuestra tienda no pasar\u00eda a modo cat\u00e1logo, seguir\u00eda siendo una tienda online.<\/p>\n<h3><strong>\u00bfQu\u00e9 Pasa al Activar el Modo Cat\u00e1logo en PrestaShop 1.7?<\/strong><\/h3>\n<p>Al activar el modo cat\u00e1logo en PrestaShop 1.7 se llevan a cabo algunas acciones sobre la propia tienda en s\u00ed; <strong>nuestra tienda online deja de ser funcional para pedidos online y pasa a ser un cat\u00e1logo online para tan solo poder consultar los productos<\/strong>, es decir, la web ya no permite la venta de productos a trav\u00e9s de Internet, por lo que tanto <strong>el carrito de compra como la posibilidad de a\u00f1adir productos al mismo desaparece por completo<\/strong> (sus m\u00f3dulos correspondientes son desactivados), aunque al menos <strong>se nos da la posibilidad de decidir si queremos que se muestren o se oculten los precios de los productos<\/strong>, tal y como ilustramos en la siguiente captura de pantalla:<\/p>\n<p><strong> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-34673\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-catalogo-sincarrito-600x371.jpg\" alt=\"PrestaShop 1.7 Cat\u00e1logo SIN Carrito\" width=\"600\" height=\"371\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-catalogo-sincarrito.jpg 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-catalogo-sincarrito-500x309.jpg 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-catalogo-sincarrito-350x216.jpg 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/strong><\/p>\n<h3><strong>\u00bfPara Qu\u00e9 Podemos Necesitar el Modo Cat\u00e1logo en PrestaShop 1.7?<\/strong><\/h3>\n<p>Es posible que no siempre necesitemos vender productos en Internet, pero si disponer de un <strong>cat\u00e1logo online<\/strong> donde poder mostrar productos a nuestros clientes o nuestras \u00faltimas novedades. De hecho, pueden ser varias las razones que nos motiven a utilizar PrestaShop 1.7 como cat\u00e1logo online en vez de como tienda online.<\/p>\n<p><strong>Podemos necesitar activar el modo cat\u00e1logo de Prestashop por:<\/strong><\/p>\n<p><strong>&#8211; Cat\u00e1logo Online:<\/strong> como ya hemos comentado la principal raz\u00f3n seguramente ser\u00e1 esta, no necesitaremos disponer de PrestaShop 1.7 en modo tienda online, sino un <strong>cat\u00e1logo online<\/strong> a modo escaparate donde mostrar nuestros productos o las \u00faltimas novedades que tengamos disponibles.<\/p>\n<p><strong>&#8211; Mantenimiento:<\/strong> tambi\u00e9n puede darse el caso de que necesitemos<strong> hacer cambios en la tienda<\/strong> y en vez de ponerla en modo mantenimiento (seamos realistas no queda muy bien) prefiramos que los productos al menos se sigan mostrando, pero sin dar a los clientes la posibilidad de hacer pedidos mientras nosotros llevamos a cabo los cambios que consideremos oportunos en la tienda. Por ejemplo, para realizar el cambio de algunos precios desfasados.<\/p>\n<p><strong>&#8211; Servicios o Presupuestos:<\/strong> esta opci\u00f3n es la menos habitual, pero <strong>podemos tener productos con precios variables y, por lo tanto, tener que hacer un presupuesto acorde a las necesidades del cliente<\/strong>. En PrestaShop 1.7 mostrar\u00edamos los productos o servicios para que los clientes contactaran con nosotros para que les hici\u00e9ramos un presupuesto a medida.<\/p>\n<p>\u00a1Y eso es todo! Como has podido comprobar <strong>activar el modo cat\u00e1logo en PrestaShop 1.7 tan solo te costar\u00e1 unos segundos y podr\u00e1s disfrutar de todos tus productos a trav\u00e9s de un cat\u00e1logo online completamente profesional<\/strong> sobre todo gracias a esta pr\u00e1ctica funcionalidad de PrestaShop 1.7.\u00a0 \ud83d\ude09<\/p>\n<h2><strong>HOSTING\u00a0PRESTASHOP\u00a0SSD CON LITESPEED<\/strong><\/h2>\n<p>En Hostinet puedes contratar un\u00a0<strong style=\"font-style: inherit;\">Hosting PrestaShop SSD<\/strong> con <a href=\"https:\/\/www.hostinet.com\/hosting-web\/litespeed-web-server-todo-lo-que-necesitas-saber\/\" target=\"_blank\" rel=\"noopener noreferrer\">LiteSpeed<\/a> para hacer que tu tienda online vaya mucho m\u00e1s r\u00e1pida que la de tu competencia. <strong style=\"font-style: inherit;\">\u00a1Te garantizamos una IP espa\u00f1ola<\/strong><strong>, as\u00ed como el mejor soporte en tu idioma<\/strong><strong>!\u00a0<\/strong><\/p>\n<p>En Hostinet trabajamos desde hace m\u00e1s de 15 a\u00f1os con servidores ubicados en Espa\u00f1a (Madrid y Bilbao) para ofrecer a nuestros clientes las mejores prestaciones posibles.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.hostinet.com\/hosting-prestashop-ssd\/\" target=\"_blank\"><img decoding=\"async\" class=\"alignnone size-full\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2026\/04\/hosting_prestashop.jpg\" alt=\"Hosting PrestaShop\"><\/a><\/p>\n<div style=\"min-height: 30px; margin-top: 0px; padding-bottom: 7px; z-index: 1;position: relative; float: none;\" class=\"social-container\"><\/div> <!-- x1 -->","protected":false},"excerpt":{"rendered":"<p>Aunque puede resultar un tanto curioso debido a la simplicidad del asunto, a veces en Hostinet recibimos consultas de nuestros clientes en la que nos indican como pueden activar el modo cat\u00e1logo en PrestaShop 1.7, es por ello por lo que en el d\u00eda de hoy vamos a indicar donde\u2026 <\/p>\n<div class=\"post-more\">\n<p><a class=\"btn button\" href=\"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/\">Sigue leyendo &rarr;<\/a><\/p>\n<\/div>\n","protected":false},"author":13,"featured_media":34672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1784,2023],"tags":[],"class_list":["post-34670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prestashop","category-prestashop-1-7"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Activar Modo Cat\u00e1logo en Prestashop 1.7<\/title>\n<meta name=\"description\" content=\"PrestaShop 1.7, al igual que otras versiones m\u00e1s antiguas del CMS, viene por defecto con el modo cat\u00e1logo integrado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Activar Modo Cat\u00e1logo en Prestashop 1.7\" \/>\n<meta property=\"og:description\" content=\"PrestaShop 1.7, al igual que otras versiones m\u00e1s antiguas del CMS, viene por defecto con el modo cat\u00e1logo integrado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/\" \/>\n<meta property=\"og:site_name\" content=\"Hostinet\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-26T15:30:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"298\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raul Alaman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Hostinet\" \/>\n<meta name=\"twitter:site\" content=\"@Hostinet\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raul Alaman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/\"},\"author\":{\"name\":\"Raul Alaman\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/person\\\/7f2d10131293f0f5f8e101ff5fc8bbff\"},\"headline\":\"Activar Modo Cat\u00e1logo en Prestashop 1.7\",\"datePublished\":\"2020-05-26T15:30:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/\"},\"wordCount\":736,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ps17-modo-catalogo.jpg\",\"articleSection\":[\"PrestaShop\",\"Prestashop 1.7\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/\",\"name\":\"Activar Modo Cat\u00e1logo en Prestashop 1.7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ps17-modo-catalogo.jpg\",\"datePublished\":\"2020-05-26T15:30:26+00:00\",\"description\":\"PrestaShop 1.7, al igual que otras versiones m\u00e1s antiguas del CMS, viene por defecto con el modo cat\u00e1logo integrado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ps17-modo-catalogo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ps17-modo-catalogo.jpg\",\"width\":600,\"height\":298,\"caption\":\"PrestaShop 1.7 modo cat\u00e1logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/prestashop\\\/activar-modo-catalogo-prestashop17\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PrestaShop\",\"item\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/category\\\/prestashop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Activar Modo Cat\u00e1logo en Prestashop 1.7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#website\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\",\"name\":\"Hostinet\",\"description\":\"Hosting y dominios en Espa\u00f1a. La mejor calidad a precios baratos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\",\"name\":\"Hostinet SLU\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/hostinet-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/hostinet-logo.jpg\",\"width\":600,\"height\":245,\"caption\":\"Hostinet SLU\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Hostinet\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/person\\\/7f2d10131293f0f5f8e101ff5fc8bbff\",\"name\":\"Raul Alaman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48b5f4b2533ad76d51832beb49c1a8944cea60b3e968885696869b92ebf7d954?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48b5f4b2533ad76d51832beb49c1a8944cea60b3e968885696869b92ebf7d954?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48b5f4b2533ad76d51832beb49c1a8944cea60b3e968885696869b92ebf7d954?s=96&r=g\",\"caption\":\"Raul Alaman\"},\"sameAs\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activar Modo Cat\u00e1logo en Prestashop 1.7","description":"PrestaShop 1.7, al igual que otras versiones m\u00e1s antiguas del CMS, viene por defecto con el modo cat\u00e1logo integrado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/","og_locale":"es_ES","og_type":"article","og_title":"Activar Modo Cat\u00e1logo en Prestashop 1.7","og_description":"PrestaShop 1.7, al igual que otras versiones m\u00e1s antiguas del CMS, viene por defecto con el modo cat\u00e1logo integrado.","og_url":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/","og_site_name":"Hostinet","article_published_time":"2020-05-26T15:30:26+00:00","og_image":[{"width":600,"height":298,"url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo.jpg","type":"image\/jpeg"}],"author":"Raul Alaman","twitter_card":"summary_large_image","twitter_creator":"@Hostinet","twitter_site":"@Hostinet","twitter_misc":{"Escrito por":"Raul Alaman","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/#article","isPartOf":{"@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/"},"author":{"name":"Raul Alaman","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/person\/7f2d10131293f0f5f8e101ff5fc8bbff"},"headline":"Activar Modo Cat\u00e1logo en Prestashop 1.7","datePublished":"2020-05-26T15:30:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/"},"wordCount":736,"commentCount":0,"publisher":{"@id":"https:\/\/www.hostinet.com\/formacion\/#organization"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo.jpg","articleSection":["PrestaShop","Prestashop 1.7"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/","url":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/","name":"Activar Modo Cat\u00e1logo en Prestashop 1.7","isPartOf":{"@id":"https:\/\/www.hostinet.com\/formacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/#primaryimage"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo.jpg","datePublished":"2020-05-26T15:30:26+00:00","description":"PrestaShop 1.7, al igual que otras versiones m\u00e1s antiguas del CMS, viene por defecto con el modo cat\u00e1logo integrado.","breadcrumb":{"@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/#primaryimage","url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo.jpg","contentUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/05\/ps17-modo-catalogo.jpg","width":600,"height":298,"caption":"PrestaShop 1.7 modo cat\u00e1logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hostinet.com\/formacion\/prestashop\/activar-modo-catalogo-prestashop17\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hostinet.com\/formacion\/"},{"@type":"ListItem","position":2,"name":"PrestaShop","item":"https:\/\/www.hostinet.com\/formacion\/category\/prestashop\/"},{"@type":"ListItem","position":3,"name":"Activar Modo Cat\u00e1logo en Prestashop 1.7"}]},{"@type":"WebSite","@id":"https:\/\/www.hostinet.com\/formacion\/#website","url":"https:\/\/www.hostinet.com\/formacion\/","name":"Hostinet","description":"Hosting y dominios en Espa\u00f1a. La mejor calidad a precios baratos","publisher":{"@id":"https:\/\/www.hostinet.com\/formacion\/#organization"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hostinet.com\/formacion\/#organization","name":"Hostinet SLU","url":"https:\/\/www.hostinet.com\/formacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/logo\/image\/","url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/06\/hostinet-logo.jpg","contentUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/06\/hostinet-logo.jpg","width":600,"height":245,"caption":"Hostinet SLU"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Hostinet"]},{"@type":"Person","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/person\/7f2d10131293f0f5f8e101ff5fc8bbff","name":"Raul Alaman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/48b5f4b2533ad76d51832beb49c1a8944cea60b3e968885696869b92ebf7d954?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/48b5f4b2533ad76d51832beb49c1a8944cea60b3e968885696869b92ebf7d954?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48b5f4b2533ad76d51832beb49c1a8944cea60b3e968885696869b92ebf7d954?s=96&r=g","caption":"Raul Alaman"},"sameAs":["https:\/\/www.hostinet.com\/formacion\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/34670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/comments?post=34670"}],"version-history":[{"count":2,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/34670\/revisions"}],"predecessor-version":[{"id":34675,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/34670\/revisions\/34675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/media\/34672"}],"wp:attachment":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/media?parent=34670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/categories?post=34670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/tags?post=34670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}