{"id":33360,"date":"2020-02-06T17:33:01","date_gmt":"2020-02-06T15:33:01","guid":{"rendered":"https:\/\/www.hostinet.com\/formacion\/?p=33360"},"modified":"2020-02-06T18:05:12","modified_gmt":"2020-02-06T16:05:12","slug":"3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source","status":"publish","type":"post","link":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/","title":{"rendered":"3 Gestores de Contrase\u00f1as para 2020 &#8211; De Pago, Gratuita y Open Source"},"content":{"rendered":" <!-- x0 --><div style=\"min-height: 30px; margin-top: 0px; padding-bottom: 7px; z-index: 1;position: relative; float: none;\" class=\"social-container\"><\/div><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-33362\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas-600x400.png\" alt=\"3 Gestores de Contrase\u00f1as para 2020 - De Pago, Gratuito y Open Source\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas.png 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas-500x333.png 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas-350x233.png 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Hace poco <a title=\"Autenticaci\u00f3n en 2 Pasos (2FA) por SMS \u2013 \u00a1Cuidado con los Hackers!\" href=\"https:\/\/www.hostinet.com\/formacion\/general\/autenticacion-en-2-pasos-2fa-por-sms-cuidado-con-los-hackers\/\" target=\"_blank\" rel=\"noopener noreferrer\">os cont\u00e1bamos<\/a>, una vez m\u00e1s, lo importante que es usar <strong>contrase\u00f1as seguras<\/strong> y <strong>no utilizar la misma contrase\u00f1a<\/strong> en distintos sitios.<\/p>\n<p>Seguir estos dos puntos mejora mucho la seguridad en cualquier login que tengamos, pero el problema es evidente&#8230;<strong>\u00bfC\u00f3mo voy a recordar tantas contrase\u00f1as distintas, seguras y aleatorias?<\/strong><\/p>\n<p>Si tienes muchos acceso es pr\u00e1cticamente imposible adem\u00e1s de engorroso, y el <em>postit<\/em> pegado en el marco de la pantalla del ordenador tampoco es viable.<\/p>\n<p>La soluci\u00f3n pasa por usar un <strong>gestor de contrase\u00f1as<\/strong> donde puedas almacenar todos las contrase\u00f1as en un mismo sitio y <strong>puedas acceder a todas ellas mediante una contrase\u00f1a maestra<\/strong>.<\/p>\n<p>Esto quiere decir que <strong><a title=\"C\u00f3mo Crear y Acordarse de Contrase\u00f1as Seguras\" href=\"https:\/\/www.hostinet.com\/formacion\/general\/crear-acordarse-contrasenas-seguras-mnemotecnia\/\" target=\"_blank\" rel=\"noopener noreferrer\">s\u00f3lo necesitar\u00e1s memorizar una contrase\u00f1a segura<\/a><\/strong> y el gestor de contrase\u00f1a se encargar\u00e1 de guardar el resto de tus contrase\u00f1as o m\u00e1s informaci\u00f3n delicada.<\/p>\n<p><strong>Existen muchos gestores de contrase\u00f1as<\/strong>, algunos de pago, otros con opciones gratuitas, con m\u00e1s o menos opciones que pueden o no, adaptarse a tus necesidades.<\/p>\n<p>Si nunca has usado un gestor de contrase\u00f1as, puede que est\u00e9s un poco perdido, as\u00ed que vamos a ver 3 gestores de contrase\u00f1as que puedes usar ahora, en 2020, cada uno de ellos con distintas caracter\u00edsticas<\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.hostinet.com\/hosting-web\/\" target=\"_blank\"><img decoding=\"async\" class=\"alignnone size-full\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2024\/03\/banner_hostinet_generico.jpg\" alt=\"Hosting Gen\u00e9rico\"><\/a><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<h2>1 &#8211; 1Password<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-33365\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/1password-600x388.png\" alt=\"1Password - Gestor de Contrase\u00f1as\" width=\"600\" height=\"388\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/1password.png 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/1password-500x323.png 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/1password-350x226.png 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>Dicen que es el gestor de contrase\u00f1as m\u00e1s completo<\/strong> y posiblemente lo sea, pero no disponen de una versi\u00f3n gratuita, as\u00ed que si quieres usarlo, tienes que pagar.<\/p>\n<p>Te ofrecen 1 mes gratis para que lo puedas probar de manera total y comprobar si es lo que est\u00e1s buscando o no.<\/p>\n<p>No creo que las opciones que <strong>1Password<\/strong> de ofrece no te gusten, depende de si quieres pagar por esa opciones o no.<\/p>\n<p>Como servicio es genial y su nombre comercial lo dice todo <em>\u00ab1 Contrase\u00f1a\u00bb<\/em>, haci\u00e9ndonos ver que <strong>s\u00f3lo necesitaremos una contrase\u00f1a<\/strong> para usarlo.<\/p>\n<p>Puedes instalarlo en <strong>Windows, en macOS, en Linux,<\/strong> en Chrome OS, en dispositivos <strong>Android<\/strong> y los i<strong>Phone\/iPad<\/strong>, adem\u00e1s dispone de extensiones para los navegadores m\u00e1s utilizados, <strong>Chrome<\/strong> y todos los basados en <em>Chromium<\/em>, <strong>Firefox<\/strong>, <strong>Safari<\/strong> y Opera.<\/p>\n<p>Cualquier <strong>contrase\u00f1a que a\u00f1adas<\/strong> en cualquiera de los dispositivos que tengas asociados a la cuenta, <strong>se sincronizar\u00e1n de forma inmediata<\/strong>.<\/p>\n<p>Adem\u00e1s puedes a\u00f1adir notas seguras, datos de tarjetas de cr\u00e9dito, identidades de usuario y si alguna de las contrase\u00f1as utilizadas es filtrada y aparece en la base de datos de <em><a title=\"C\u00f3mo Saber si tu Cuenta de Correo est\u00e1 en Peligro de ser Hackeada\" href=\"https:\/\/www.hostinet.com\/formacion\/correo-electronico\/como-saber-si-tu-cuenta-de-correo-esta-en-peligro-de-ser-hackeada\/\" target=\"_blank\" rel=\"noopener noreferrer\">have i been pwned?<\/a><\/em>, te avisar\u00e1 para que la cambies.<\/p>\n<p>Como ver\u00e1s, un todo en uno, con multitud de servicios y multimplataforma, con el <em>handicap<\/em> del precio, <strong>ya que precio m\u00e1s econ\u00f3mico es de 35,88 $ + impuestos<\/strong>.<\/p>\n<h3>&#8211; <a title=\"Sitio Web de 1Password\" href=\"https:\/\/1password.com\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Web 1Password<\/a><\/h3>\n<p>&nbsp;<\/p>\n<h2>2 &#8211; LastPass<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-33367\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/lastpass-600x338.png\" alt=\"LastPass - Gestor de Contrase\u00f1as\" width=\"600\" height=\"338\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/lastpass.png 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/lastpass-500x282.png 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/lastpass-350x197.png 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>LastPass<\/strong> es uno de los gestores de contrase\u00f1as m\u00e1s populares en la actualidad y no es de extra\u00f1ar.<\/p>\n<p><strong>Ofrece una versi\u00f3n gratuita<\/strong> que, posiblemente, sea <strong>suficiente para muchos de usuarios<\/strong>, aunque tambi\u00e9n disponen de opciones de pago con m\u00e1s funcionalidades, en el caso de necesitarla.<\/p>\n<p>Al darde de alta en la versi\u00f3n gratuita, <strong>te dan acceso a las opciones <em>premium<\/em> durante 30 d\u00edas<\/strong>, opciones como compartir contrase\u00f1as, soporte t\u00e9cnico prioritario o caracter\u00edsticas avanzadas de acceso con m\u00faltiples factores.<\/p>\n<p>Si tu intenci\u00f3n es no pagar, mejor que no te encari\u00f1es con las opciones <em>premium<\/em>&#8230;<\/p>\n<p>Tambi\u00e9n es multiplataforma, <strong>Android, iOS, Mac y Windows<\/strong>, parece que no hay aplicaci\u00f3n para Linux, pero si extensiones para todos los navegadores populares, <strong>Chrome, Safari, Firefox, etc&#8230;<\/strong><\/p>\n<p>La <strong>versi\u00f3n gratuita de LastPass no tiene l\u00edmite de contrase\u00f1as guardadas<\/strong>, al menos aparentemente, ni tampoco pone <strong>l\u00edmites al n\u00famero de dispositivos<\/strong> que pueden usar la misma cuenta, algo muy de agradecer.<\/p>\n<p>Las versiones de pago ofrecen herramientas interesantes, como la posibilidad de <strong>utilizar una llave USB para una autenticaci\u00f3n 2FA<\/strong> muy segura, <strong>1 GB de espacio online<\/strong> totalmente encriptado o compartir contrase\u00f1as y otros datos con otros usuarios de confianza.<\/p>\n<p>La versi\u00f3n de pago m\u00e1s econ\u00f3mica tiene un precio de 32,04 \u20ac, pero como hemos comentado, <strong>tienes 30 d\u00edas para probar las opciones <em>pro<\/em> en la versi\u00f3n gratuita<\/strong>.<\/p>\n<h3>&#8211; <a title=\"LastPass\" href=\"https:\/\/www.lastpass.com\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Web LastPass<\/a><\/h3>\n<p>&nbsp;<\/p>\n<h2>3 &#8211; KeePass Password Safe<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-33369\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/keepass-600x459.png\" alt=\"KeePass Password Safe\" width=\"600\" height=\"459\" srcset=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/keepass.png 600w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/keepass-500x383.png 500w, https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/keepass-350x268.png 350w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Si prefieres usar una aplicaci\u00f3n de c\u00f3digo abierto y no privativo, una de las opciones m\u00e1s populares que puedes encontrar es <strong>KeePass Password Safe<\/strong>.<\/p>\n<p><strong>KeePass<\/strong> no tiene la presencia visual que tienen otros gestores de contrase\u00f1as propietarios, pero <strong>al ser una soluci\u00f3n <em>Open Source<\/em><\/strong>, nos aseguramos que <strong>nuestros datos no pasan por ninguna empresa propietaria<\/strong> del software.<\/p>\n<p>Dispone de versiones <em>portables<\/em> que no necesitan de instalaci\u00f3n para funcionar, algo que puede ser <strong>muy interesante para algunos usuarios<\/strong>.<\/p>\n<p>Al contrario que otras opciones, <strong>KeePass<\/strong> trabaja de forma local, esto quiere decir que <strong>la base de datos<\/strong> que almacena nuestras contrase\u00f1as <strong>se encuentra en nuestro ordenador<\/strong> y no en un servidor externo.<\/p>\n<p>La parte buena de esto es que es m\u00e1s seguro, pero si le pasa algo a nuestro ordenador y no disponemos de una copia de seguridad, <strong>adi\u00f3s a nuestras contrase\u00f1as<\/strong>.<\/p>\n<p>Aunque si hay algo que caracteriza a <strong>KeePass<\/strong>, es la cantidad de <strong>plugins<\/strong> que tiene disponibles.<\/p>\n<p>Estos plugins sirven para <strong>a\u00f1adir funcionalidades extra<\/strong> al gestor de contrase\u00f1as, incluido el soporte a <strong>la sincronizaci\u00f3n online con proveedores<\/strong> de terceras partes, para as\u00ed sincronizarlo con todos nuestros dispositivos.<\/p>\n<p>Hay muchos otros plugins disponibles, pero s\u00f3lo tenemos que usar los que nos interesen, creando as\u00ed u<strong>na aplicaci\u00f3n muy ligera y modular<\/strong>, sin duda uno de sus puntos fuertes.<\/p>\n<p>La aplicaci\u00f3n est\u00e1 disponible para Windows, <strong>pero existen muchas otras aplicaciones creadas por la comunidad<\/strong>, que ofrecen soporte a casi todos los sistemas operativos, al igual que extensiones para los navegadores.<\/p>\n<p><strong>KeePass<\/strong> es una opci\u00f3n muy interesante, por lo plugins que ofrece y por ser <em>Open Source<\/em>, aunque la elecci\u00f3n es siempre personal, claro.<\/p>\n<h3>&#8211; <a title=\"KeePass Password Safe\" href=\"https:\/\/keepass.info\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Web KeePass<\/a><\/h3>\n<p>&nbsp;<\/p>\n<h2>Cosas a Tener en Cuenta<\/h2>\n<p>Est\u00e1 claro que <strong>utilizar un gestor de contrase\u00f1as<\/strong> es algo que nos ayuda a <strong>mejorar nuestra seguridad online<\/strong>, sobre todo porque nos ayuda a <strong>huir de la mala costumbre de repetir contrase\u00f1as<\/strong>.<\/p>\n<p>Sobre lo de utilizar un gestor de contrase\u00f1as de pago o gratuito, cada uno puede tomar su propia decisi\u00f3n.<\/p>\n<p>Por el lado personal, entendemos que si tiene unas pocas contrase\u00f1as que guardar<strong>, una versi\u00f3n gratuita<\/strong> de cualquier gestor <strong>puede ser suficiente<\/strong>.<\/p>\n<p>Si tienes <strong>cientos de accesos con distintos logins<\/strong>, quiz\u00e1s necesites m\u00e1s opciones para gestionar todo correctamente y <strong>pagar un pu\u00f1ado de euros al a\u00f1o no te importe<\/strong>.<\/p>\n<p>En cualquier caso, usar un gestor de contrase\u00f1as es una buena idea, sea la opci\u00f3n que sea, pero eso si,<strong>\u00a1\u00a1no olvides la contrase\u00f1a maestra!!<\/strong>.<\/p>\n<h1>Hosting SSD con IP Espa\u00f1ola<\/h1>\n<p><a href=\"https:\/\/www.hostinet.com\/hosting-ssd\/\" target=\"_blank\"><img decoding=\"async\" class=\"alignnone size-full\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2026\/04\/banner_hosting_web_v2.jpg\" alt=\"Hosting SSD NVMe\"><\/a><\/p>\n<div style=\"min-height: 30px; margin-top: 0px; padding-bottom: 7px; z-index: 1;position: relative; float: none;\" class=\"social-container\"><\/div> <!-- x1 -->","protected":false},"excerpt":{"rendered":"<p>Hace poco os cont\u00e1bamos, una vez m\u00e1s, lo importante que es usar contrase\u00f1as seguras y no utilizar la misma contrase\u00f1a en distintos sitios. Seguir estos dos puntos mejora mucho la seguridad en cualquier login que tengamos, pero el problema es evidente&#8230;\u00bfC\u00f3mo voy a recordar tantas contrase\u00f1as distintas, seguras y aleatorias?\u2026 <\/p>\n<div class=\"post-more\">\n<p><a class=\"btn button\" href=\"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/\">Sigue leyendo &rarr;<\/a><\/p>\n<\/div>\n","protected":false},"author":14,"featured_media":33362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-33360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 Gestores de Contrase\u00f1as para 2020 - De Pago, Gratuita y Open Source<\/title>\n<meta name=\"description\" content=\"Hace poco os cont\u00e1bamos, una vez m\u00e1s, lo importante que es usar contrase\u00f1as seguras y no utilizar la misma contrase\u00f1a en distintos sitios. Seguir estos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 Gestores de Contrase\u00f1as para 2020 - De Pago, Gratuita y Open Source\" \/>\n<meta property=\"og:description\" content=\"Hace poco os cont\u00e1bamos, una vez m\u00e1s, lo importante que es usar contrase\u00f1as seguras y no utilizar la misma contrase\u00f1a en distintos sitios. Seguir estos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/\" \/>\n<meta property=\"og:site_name\" content=\"Hostinet\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-06T15:33:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T16:05:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marce Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Hostinet\" \/>\n<meta name=\"twitter:site\" content=\"@Hostinet\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marce Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/\"},\"author\":{\"name\":\"Marce Medina\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/person\\\/c30f2ada08e5d4836b12fd3782d3958f\"},\"headline\":\"3 Gestores de Contrase\u00f1as para 2020 &#8211; De Pago, Gratuita y Open Source\",\"datePublished\":\"2020-02-06T15:33:01+00:00\",\"dateModified\":\"2020-02-06T16:05:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/\"},\"wordCount\":1164,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/3-gestores-contrasenas.png\",\"articleSection\":[\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/\",\"name\":\"3 Gestores de Contrase\u00f1as para 2020 - De Pago, Gratuita y Open Source\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/3-gestores-contrasenas.png\",\"datePublished\":\"2020-02-06T15:33:01+00:00\",\"dateModified\":\"2020-02-06T16:05:12+00:00\",\"description\":\"Hace poco os cont\u00e1bamos, una vez m\u00e1s, lo importante que es usar contrase\u00f1as seguras y no utilizar la misma contrase\u00f1a en distintos sitios. Seguir estos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/3-gestores-contrasenas.png\",\"contentUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/3-gestores-contrasenas.png\",\"width\":600,\"height\":400,\"caption\":\"3 Gestores de Contrase\u00f1as para 2020 - De Pago, Gratuito y Open Source\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/general\\\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"General\",\"item\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/category\\\/general\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"3 Gestores de Contrase\u00f1as para 2020 &#8211; De Pago, Gratuita y Open Source\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#website\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\",\"name\":\"Hostinet\",\"description\":\"Hosting y dominios en Espa\u00f1a. La mejor calidad a precios baratos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\",\"name\":\"Hostinet SLU\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/hostinet-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/hostinet-logo.jpg\",\"width\":600,\"height\":245,\"caption\":\"Hostinet SLU\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Hostinet\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/person\\\/c30f2ada08e5d4836b12fd3782d3958f\",\"name\":\"Marce Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g\",\"caption\":\"Marce Medina\"},\"sameAs\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 Gestores de Contrase\u00f1as para 2020 - De Pago, Gratuita y Open Source","description":"Hace poco os cont\u00e1bamos, una vez m\u00e1s, lo importante que es usar contrase\u00f1as seguras y no utilizar la misma contrase\u00f1a en distintos sitios. Seguir estos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/","og_locale":"es_ES","og_type":"article","og_title":"3 Gestores de Contrase\u00f1as para 2020 - De Pago, Gratuita y Open Source","og_description":"Hace poco os cont\u00e1bamos, una vez m\u00e1s, lo importante que es usar contrase\u00f1as seguras y no utilizar la misma contrase\u00f1a en distintos sitios. Seguir estos","og_url":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/","og_site_name":"Hostinet","article_published_time":"2020-02-06T15:33:01+00:00","article_modified_time":"2020-02-06T16:05:12+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas.png","type":"image\/png"}],"author":"Marce Medina","twitter_card":"summary_large_image","twitter_creator":"@Hostinet","twitter_site":"@Hostinet","twitter_misc":{"Escrito por":"Marce Medina","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/#article","isPartOf":{"@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/"},"author":{"name":"Marce Medina","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/person\/c30f2ada08e5d4836b12fd3782d3958f"},"headline":"3 Gestores de Contrase\u00f1as para 2020 &#8211; De Pago, Gratuita y Open Source","datePublished":"2020-02-06T15:33:01+00:00","dateModified":"2020-02-06T16:05:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/"},"wordCount":1164,"commentCount":0,"publisher":{"@id":"https:\/\/www.hostinet.com\/formacion\/#organization"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas.png","articleSection":["General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/","url":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/","name":"3 Gestores de Contrase\u00f1as para 2020 - De Pago, Gratuita y Open Source","isPartOf":{"@id":"https:\/\/www.hostinet.com\/formacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/#primaryimage"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas.png","datePublished":"2020-02-06T15:33:01+00:00","dateModified":"2020-02-06T16:05:12+00:00","description":"Hace poco os cont\u00e1bamos, una vez m\u00e1s, lo importante que es usar contrase\u00f1as seguras y no utilizar la misma contrase\u00f1a en distintos sitios. Seguir estos","breadcrumb":{"@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/#primaryimage","url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas.png","contentUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2020\/02\/3-gestores-contrasenas.png","width":600,"height":400,"caption":"3 Gestores de Contrase\u00f1as para 2020 - De Pago, Gratuito y Open Source"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hostinet.com\/formacion\/general\/3-gestores-de-contrasenas-para-2020-de-pago-gratuita-open-source\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hostinet.com\/formacion\/"},{"@type":"ListItem","position":2,"name":"General","item":"https:\/\/www.hostinet.com\/formacion\/category\/general\/"},{"@type":"ListItem","position":3,"name":"3 Gestores de Contrase\u00f1as para 2020 &#8211; De Pago, Gratuita y Open Source"}]},{"@type":"WebSite","@id":"https:\/\/www.hostinet.com\/formacion\/#website","url":"https:\/\/www.hostinet.com\/formacion\/","name":"Hostinet","description":"Hosting y dominios en Espa\u00f1a. La mejor calidad a precios baratos","publisher":{"@id":"https:\/\/www.hostinet.com\/formacion\/#organization"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hostinet.com\/formacion\/#organization","name":"Hostinet SLU","url":"https:\/\/www.hostinet.com\/formacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/logo\/image\/","url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/06\/hostinet-logo.jpg","contentUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/06\/hostinet-logo.jpg","width":600,"height":245,"caption":"Hostinet SLU"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Hostinet"]},{"@type":"Person","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/person\/c30f2ada08e5d4836b12fd3782d3958f","name":"Marce Medina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g","caption":"Marce Medina"},"sameAs":["https:\/\/www.hostinet.com\/formacion\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/33360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/comments?post=33360"}],"version-history":[{"count":6,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/33360\/revisions"}],"predecessor-version":[{"id":33370,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/33360\/revisions\/33370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/media\/33362"}],"wp:attachment":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/media?parent=33360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/categories?post=33360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/tags?post=33360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}