{"id":14474,"date":"2016-01-19T13:18:03","date_gmt":"2016-01-19T11:18:03","guid":{"rendered":"https:\/\/www.hostinet.com\/formacion\/?p=14474"},"modified":"2016-01-19T13:33:37","modified_gmt":"2016-01-19T11:33:37","slug":"como-subir-archivos-a-la-web-con-panel-control-plesk","status":"publish","type":"post","link":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/","title":{"rendered":"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk"},"content":{"rendered":" <!-- x0 --><div style=\"min-height: 30px; margin-top: 0px; padding-bottom: 7px; z-index: 1;position: relative; float: none;\" class=\"social-container\"><\/div><p>\n\t<img loading=\"lazy\" decoding=\"async\" alt=\"subir website con plesk \" class=\"aligncenter size-medium wp-image-14476\" height=\"234\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/subir-website-plesk-600x234.jpg\" width=\"600\" \/>\n<\/p>\n<p>\n\tUna vez tengas hayas contratado tu hosting lo m&aacute;s seguro es que quieras subir archivos a la Web que hayas creado para que sea visible a todo el mundo.\n<\/p>\n<p>\n\tPara poder subir archivos puedes hacerlo a trav&eacute;s de un cliente FTP o <strong>directamente desde el panel de control Plesk<\/strong>.\n<\/p>\n<h2>\n\t<br \/>\n\tSubir Archivos Usando Cliente FTP<br \/>\n<\/h2>\n<p>\n\tEn cualquier caso debes de tener en cuenta que para acceder al FTP con un cliente debes a&ntilde;adir un nombre de Host de esta forma:\n<\/p>\n<pre>\r\n<code>ftp.midominio.info\r\n<\/code><\/pre>\n<p>\n\tAdem&aacute;s deber&aacute;s a&ntilde;adir en nombre de usuario y contrase&ntilde;a que <strong>enviamos en el email de activaci&oacute;n<\/strong>.\n<\/p>\n<p>\n\tUna vez accedas al FTP ver&aacute;s que ya hay creados algunos directorios. <strong>No borres ninguno<\/strong> ya que todos tiene una raz&oacute;n para estar ah&iacute; y lo &uacute;nico que causar&aacute;s ser&aacute;n inconvenientes para el correcto funcionamiento de tu sitio Web.\n<\/p>\n<p>\n\t<img loading=\"lazy\" decoding=\"async\" alt=\"No borrar ning\u00fan directorio\" class=\"aligncenter size-full wp-image-14477\" height=\"158\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/archivos-no-borrar.jpg\" width=\"550\" \/>\n<\/p>\n<p>\n\tEl directorio en el que tienes que subir tu sitio Web o instalar cualquier CMS es el de <strong>httpdocs<\/strong>. En ese directorio debes subir los archivos para que cuando los usuarios pongan el nombre de tu dominio en la barra de direcciones de su navegador puedan acceder directamente a tu sitio Web.\n<\/p>\n<blockquote>\n<p>\n\t\tNo hay que borrar ning&uacute;n directorio. Todos est&aacute;n ah&iacute; por alg&uacute;n motivo.\n\t<\/p>\n<\/blockquote>\n<p>\n\t<br \/>\n\tTen en cuenta que si ha creado tu sitio Web de manera local en tu ordenador y lo subes via FTP debe existir un archivo llamado <strong>index.html o index.(otra extensi&oacute;n)<\/strong> en el directorio <strong> httpdocs<\/strong> para que funcione bien.\n<\/p>\n<p>\n\tDe no existir ese archivo s&oacute;lo se mostrar&aacute; un listado de archivos pero no un sitio Web.\n<\/p>\n<p>\n\tRecuerda que si acabas de adquirir el dominio es posible <strong>que las DNS no se hayan propagado<\/strong> as&iacute; que espera al menos 48 horas o usa la direcci&oacute;n IP en lugar del dominio si no puedes acceder a el.<br \/>\n\t&nbsp;\n<\/p>\n<p>\n\t[ninja-popup ID=13602] *<strong><span style=\"color:#FFFFFF;\"><span style=\"background-color:#FF0000;\"> AP&Uacute;NTATE GRATIS<\/span><\/span> y aprender&aacute;s todo lo que puedes hacer con el panel de control Plesk.&nbsp;<span style=\"color:#FFFFFF;\"><span style=\"background-color:#FF0000;\"> CLICK AQU&Iacute; <\/span><\/span><\/strong> [\/ninja-popup]\n<\/p>\n<h2>\n\t<br \/>\n\tSubir Archivos Usando Panel Plesk<br \/>\n<\/h2>\n<p>\n\t<strong>Plesk<\/strong> tambi&eacute;n posibilita la subida de archivos Web a trav&eacute;s de su propio panel.\n<\/p>\n<p>\n\tAct&uacute;a como cualquier cliente FTP ya que podremos subir y bajar archivos, crear directorios, cambiar el nombre e <strong>incluso los permisos de cada archivo y directorio<\/strong>.\n<\/p>\n<p>\n\tPara poder usar subir nuestro sitio Web directamente desde Plesk lo primero que debemos hacer es acceder a Plesk desde con nuestro usuario y contrase&ntilde;a. Para acceder al panel de control Plesk recuerda que puedes hacerlo mediante este formato de URL:\n<\/p>\n<pre>\r\n<code>https:\/\/www.midominio.info:8443\r\n<\/code><\/pre>\n<p>\n\tSi tienes alguna duda o alg&uacute;n problema para entrar puedes ver la entrada que creamos de <strong><a href=\"https:\/\/www.hostinet.com\/formacion\/plesk\/como-acceder-al-panel-de-control-plesk\/\" target=\"_blank\" title=\"C\u00f3mo Acceder al Panel de Control Plesk\">C&oacute;mo Acceder al Panel de Control Plesk<\/a><\/strong>.\n<\/p>\n<p>\n\tUna vez estemos dentro del Plesk debemos hacer click en el <strong>Archivos<\/strong> en el men&uacute; lateral.\n<\/p>\n<p>\n\t<img loading=\"lazy\" decoding=\"async\" alt=\"archivos menu lateral en Plesk\" class=\"aligncenter size-full wp-image-14478\" height=\"313\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/archivos-menu-lateral.jpg\" width=\"422\" \/>\n<\/p>\n<p>\n\tEl acceso es inmediato y no deber&aacute;s a&ntilde;adir ning&uacute;n nombre de usuario o contrase&ntilde;a. Ver&aacute;s que hay varios directorios creados. Volvemos a insistir en que <strong>no se elimine ninguno<\/strong>.\n<\/p>\n<p>\n\t<img loading=\"lazy\" decoding=\"async\" alt=\"administrador de archivos de Plesk\" class=\"aligncenter size-medium wp-image-14479\" height=\"226\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/administrador-de-archivos-600x226.jpg\" width=\"600\" \/>\n<\/p>\n<p>\n\tComo hemos comentado antes, el directorio donde debemos subir nuestro sitio Web es <strong>httpdocs<\/strong>. Hacemos click en el y veremos que ya existen algunos archivos. Como veremos ya existe un <strong>index.html<\/strong>. Esto es porque cuando se instala el panel Plesk se crea un p&aacute;gina de prueba. Cuando subas tu sitio Web deber&aacute;s eliminar ese index o sustituirlo por el correcto.\n<\/p>\n<p>\n\tEn la parte superior veremos que tenemos las t&iacute;picas acciones de Copiar, Mover, Eliminar, etc..\n<\/p>\n<p>\n\tTambi&eacute;n nos da la posibilidad de <strong>Cargar<\/strong> as&iacute; que hacemos click nos abrir&aacute; una ventada de archivos para que localicemos el archivo que queramos subir.\n<\/p>\n<p>\n\tUna vez seleccionado hacemos click en <strong>Abrir<\/strong> o <strong>Subir<\/strong> y Plesk a&ntilde;adir&aacute; el archivo al directorio donde nos encontr&aacute;ramos.\n<\/p>\n<p>\n\t<img loading=\"lazy\" decoding=\"async\" alt=\"prueba archivo subido en Plesk\" class=\"aligncenter size-medium wp-image-14480\" height=\"314\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/prueba-plesk-600x314.jpg\" width=\"600\" \/>\n<\/p>\n<p>\n\tRecuerda que <strong>no podr&aacute;s subir directorios directamente<\/strong>. Deber&aacute;s crearlos en el <strong>Administrador de archivos<\/strong> y luego subir los archivos.\n<\/p>\n<hr \/>\n<h2>\n\t<br \/>\n\t<strong>Planes Windows Econ&oacute;micos<\/strong><br \/>\n<\/h2>\n<p>\n\tEn Hostinet disponemos de una amplia variedad de <strong><a href=\"https:\/\/www.hostinet.com\/hosting-web\/planes-windows\/\" target=\"_blank\" title=\"planes de alojamiento Windows en Hostinet\">Hosting Windows<\/a><\/strong>, por ejemplo, <strong>desde tan solo 2 euros al mes puedes contratar un plan Win B&aacute;sico<\/strong>, dise&ntilde;ado para ofrecer un alto rendimiento a todo tipo de p&aacute;ginas Web, ya sean blogs personales o p&aacute;ginas empresariales.\n<\/p>\n<p style=\"text-align: center;\">\n\t<a href=\"http:\/\/www.hostinet.com\/hosting-web\/planes-windows\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/hosting-windows1.jpg\" \/><\/a>\n<\/p>\n<p>\n\tTe recordamos que <strong>todos nuestros Hosting Windows disponen de acceso al panel de control Plesk de manera gratuita <\/strong>para poder gestionar tu servidor y tus propias cuentas de email de forma sencilla.\n<\/p>\n<p>\n\tEn Hostinet trabajamos desde hace m&aacute;s de 14 a&ntilde;os con servidores ubicados en Espa&ntilde;a; ofreciendo un precio de calidad, una seguridad impenetrable y una confianza sin igual a todos nuestros clientes.\n<\/p>\n<p>\n\t<strong>HOSTINET = SEGURIDAD + CONFIANZA + PRECIO + 14 A&Ntilde;OS DE EXPERIENCIA<\/strong><\/p>\n<div style=\"min-height: 30px; margin-top: 0px; padding-bottom: 7px; z-index: 1;position: relative; float: none;\" class=\"social-container\"><\/div> <!-- x1 -->","protected":false},"excerpt":{"rendered":"<p>Una vez tengas hayas contratado tu hosting lo m&aacute;s seguro es que quieras subir archivos a la Web que hayas creado para que sea visible a todo el mundo. Para poder subir archivos puedes hacerlo a trav&eacute;s de un cliente FTP o directamente desde el panel de control Plesk. Subir\u2026 <\/p>\n<div class=\"post-more\">\n<p><a class=\"btn button\" href=\"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/\">Sigue leyendo &rarr;<\/a><\/p>\n<\/div>\n","protected":false},"author":14,"featured_media":14476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1828],"tags":[],"class_list":["post-14474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-plesk"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk<\/title>\n<meta name=\"description\" content=\"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk. Con Plesk podr\u00e1s subir tus archivos a la Web desde el panel de control. Es muy sencillo, s\u00f3lo...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk. Con Plesk podr\u00e1s subir tus archivos a la Web desde el panel de control. Es muy sencillo, s\u00f3lo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/\" \/>\n<meta property=\"og:site_name\" content=\"Hostinet\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-19T11:18:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-19T11:33:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/subir-website-plesk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"234\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marce Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Hostinet\" \/>\n<meta name=\"twitter:site\" content=\"@Hostinet\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marce Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/\"},\"author\":{\"name\":\"Marce Medina\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/person\\\/c30f2ada08e5d4836b12fd3782d3958f\"},\"headline\":\"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk\",\"datePublished\":\"2016-01-19T11:18:03+00:00\",\"dateModified\":\"2016-01-19T11:33:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/\"},\"wordCount\":842,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/subir-website-plesk.jpg\",\"articleSection\":[\"Plesk\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/\",\"name\":\"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/subir-website-plesk.jpg\",\"datePublished\":\"2016-01-19T11:18:03+00:00\",\"dateModified\":\"2016-01-19T11:33:37+00:00\",\"description\":\"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk. Con Plesk podr\u00e1s subir tus archivos a la Web desde el panel de control. Es muy sencillo, s\u00f3lo...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/subir-website-plesk.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/subir-website-plesk.jpg\",\"width\":600,\"height\":234,\"caption\":\"subir website con plesk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/plesk\\\/como-subir-archivos-a-la-web-con-panel-control-plesk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plesk\",\"item\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/category\\\/plesk\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#website\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\",\"name\":\"Hostinet\",\"description\":\"Hosting y dominios en Espa\u00f1a. La mejor calidad a precios baratos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#organization\",\"name\":\"Hostinet SLU\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/hostinet-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/hostinet-logo.jpg\",\"width\":600,\"height\":245,\"caption\":\"Hostinet SLU\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Hostinet\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/#\\\/schema\\\/person\\\/c30f2ada08e5d4836b12fd3782d3958f\",\"name\":\"Marce Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g\",\"caption\":\"Marce Medina\"},\"sameAs\":[\"https:\\\/\\\/www.hostinet.com\\\/formacion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk","description":"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk. Con Plesk podr\u00e1s subir tus archivos a la Web desde el panel de control. Es muy sencillo, s\u00f3lo...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk","og_description":"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk. Con Plesk podr\u00e1s subir tus archivos a la Web desde el panel de control. Es muy sencillo, s\u00f3lo...","og_url":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/","og_site_name":"Hostinet","article_published_time":"2016-01-19T11:18:03+00:00","article_modified_time":"2016-01-19T11:33:37+00:00","og_image":[{"width":600,"height":234,"url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/subir-website-plesk.jpg","type":"image\/jpeg"}],"author":"Marce Medina","twitter_card":"summary_large_image","twitter_creator":"@Hostinet","twitter_site":"@Hostinet","twitter_misc":{"Escrito por":"Marce Medina","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/#article","isPartOf":{"@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/"},"author":{"name":"Marce Medina","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/person\/c30f2ada08e5d4836b12fd3782d3958f"},"headline":"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk","datePublished":"2016-01-19T11:18:03+00:00","dateModified":"2016-01-19T11:33:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/"},"wordCount":842,"commentCount":0,"publisher":{"@id":"https:\/\/www.hostinet.com\/formacion\/#organization"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/subir-website-plesk.jpg","articleSection":["Plesk"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/","url":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/","name":"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk","isPartOf":{"@id":"https:\/\/www.hostinet.com\/formacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/#primaryimage"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/subir-website-plesk.jpg","datePublished":"2016-01-19T11:18:03+00:00","dateModified":"2016-01-19T11:33:37+00:00","description":"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk. Con Plesk podr\u00e1s subir tus archivos a la Web desde el panel de control. Es muy sencillo, s\u00f3lo...","breadcrumb":{"@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/#primaryimage","url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/subir-website-plesk.jpg","contentUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/01\/subir-website-plesk.jpg","width":600,"height":234,"caption":"subir website con plesk"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hostinet.com\/formacion\/plesk\/como-subir-archivos-a-la-web-con-panel-control-plesk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hostinet.com\/formacion\/"},{"@type":"ListItem","position":2,"name":"Plesk","item":"https:\/\/www.hostinet.com\/formacion\/category\/plesk\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo Subir Archivos a la Web con el Panel de Control Plesk"}]},{"@type":"WebSite","@id":"https:\/\/www.hostinet.com\/formacion\/#website","url":"https:\/\/www.hostinet.com\/formacion\/","name":"Hostinet","description":"Hosting y dominios en Espa\u00f1a. La mejor calidad a precios baratos","publisher":{"@id":"https:\/\/www.hostinet.com\/formacion\/#organization"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hostinet.com\/formacion\/#organization","name":"Hostinet SLU","url":"https:\/\/www.hostinet.com\/formacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/logo\/image\/","url":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/06\/hostinet-logo.jpg","contentUrl":"https:\/\/www.hostinet.com\/formacion\/wp-content\/uploads\/2016\/06\/hostinet-logo.jpg","width":600,"height":245,"caption":"Hostinet SLU"},"image":{"@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Hostinet"]},{"@type":"Person","@id":"https:\/\/www.hostinet.com\/formacion\/#\/schema\/person\/c30f2ada08e5d4836b12fd3782d3958f","name":"Marce Medina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a5f9094a8c7354a8f35685f8ee6e2089cfd977a0e269cab521f33c67ea47559?s=96&r=g","caption":"Marce Medina"},"sameAs":["https:\/\/www.hostinet.com\/formacion\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/14474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/comments?post=14474"}],"version-history":[{"count":6,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/14474\/revisions"}],"predecessor-version":[{"id":14486,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/posts\/14474\/revisions\/14486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/media\/14476"}],"wp:attachment":[{"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/media?parent=14474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/categories?post=14474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hostinet.com\/formacion\/wp-json\/wp\/v2\/tags?post=14474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}